{"id":165355,"date":"2024-03-20T00:00:30","date_gmt":"2024-03-20T00:00:30","guid":{"rendered":"https:\/\/www.portalminero.com\/wp\/alemania-busca-afianzar-su-presencia-en-exponor-2024\/"},"modified":"2024-03-20T17:56:53","modified_gmt":"2024-03-20T17:56:53","slug":"alemania-busca-afianzar-su-presencia-en-exponor-2024","status":"publish","type":"post","link":"https:\/\/www.portalminero.com\/wp\/alemania-busca-afianzar-su-presencia-en-exponor-2024\/","title":{"rendered":"Alemania busca afianzar su presencia en Exponor 2024"},"content":{"rendered":"<h6><em>Chile<\/em><\/h6>\n<p><b>Ofrecer innovaciones, nuevas tecnolog\u00edas, equipamiento y m\u00e1s para, responder a las necesidades de la industria minera y energ\u00e9tica, forman parte de la oferta que traer\u00e1 a nuestro pa\u00eds.<\/b><\/p>\n<p><img class=\"imagen-noticia\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/pm.portalminero.com\/images\/noticias\/65fb154271de7.jpg\" alt=\"Alemania busca afianzar su presencia en Exponor 2024\" \/><noscript><img class=\"imagen-noticia\" src=\"http:\/\/pm.portalminero.com\/images\/noticias\/65fb154271de7.jpg\" alt=\"Alemania busca afianzar su presencia en Exponor 2024\" \/><\/noscript><\/p>\n<div class=\"texto_prensa\" align=\"justify\"><strong>mi\u00e9rcoles 20 de marzo del 2024.-<\/strong> Con la confirmaci\u00f3n ya de 50 empresas, transform\u00e1ndola en la segunda mayor delegaci\u00f3n despu\u00e9s de China que dir\u00e1 presente del 3 al 6 de junio en Antofagasta y la primera en completarse, Alemania prepara su participaci\u00f3n en Exponor 2024, cantidad que podr\u00eda aumentar en n\u00famero de expositores, dada la alta demanda de compa\u00f1\u00edas germanas en asistir.<\/p>\n<p>\u201cActualmente contamos con m\u00e1s de 1000 metros cuadrados y m\u00e1s de 50 expositores para esta versi\u00f3n de Exponor, siendo uno de los Pabellones Pa\u00eds m\u00e1s grande. Esta alta demanda se debe al gran inter\u00e9s que tienen los proveedores alemanes en Chile y viceversa. Alemania es un proveedor de tecnolog\u00edas clave para distintas industrias nacionales, siendo ciertamente la miner\u00eda y energ\u00eda sectores claves en este \u00e1mbito\u201d, se\u00f1al\u00f3 Iris Wunderlich, Project Leader Mining &amp; Sustainability | AHK Chile, C\u00e1mara de Comercio Chileno-Alemana, organizadores del Pabell\u00f3n de Alemania.<\/p>\n<p>El alto inter\u00e9s en participar, a juicio de Wunderlich, obedece a las condiciones geogr\u00e1ficas ideales que presenta nuestro pa\u00eds, \u201csiendo \u00f3ptimos para la generaci\u00f3n renovable y para desarrollar una industria de hidr\u00f3geno verde, adem\u00e1s de poseer las condiciones geol\u00f3gicas para al desarrollo sostenible de los recursos minerales necesarios para la transici\u00f3n energ\u00e9tica y la descarbonizaci\u00f3n a nivel global\u201d.<\/p>\n<p><strong>Rol clave<\/strong><\/p>\n<p>Bajo esta l\u00f3gica, Alemania y sus empresas juegan un rol importante en impulsar la transici\u00f3n energ\u00e9tica, poniendo a disposici\u00f3n tecnolog\u00edas y soluciones innovadoras, posicion\u00e1ndolos como uno de los l\u00edderes en el desarrollo minero-energ\u00e9tico.<\/p>\n<p>Para seguir por este camino, recalca la ejecutiva a cargo del pabell\u00f3n, el gigante europeo requiere de los recursos minerales que Chile es capaz de proveer, como el litio, con el fin de seguir impulsando las nuevas tecnolog\u00edas de almacenamiento y electromovilidad. \u201cAs\u00ed, se establece una vinculaci\u00f3n natural, con sinergias virtuosas entre ambos pa\u00edses. Por ende, la industria alemana feliz sigue la invitaci\u00f3n de Chile y sobre todo de Exponor para seguir profundizando los lazos este 2024\u201d, sentencia.<\/p>\n<p>As\u00ed los proveedores alemanes, que tradicionalmente ofrecen productos de alta calidad para la soluci\u00f3n de desaf\u00edos tecnol\u00f3gicos, ven a Exponor como la plataforma ideal para mostrar nuevas tecnolog\u00edas, maquinarias, equipamiento y soluciones tecnol\u00f3gicas altamente especializadas, eficientes y seguras para la industria minera y\/o energ\u00e9tica, donde la sustentabilidad y la eficiencia, sea energ\u00e9tica o h\u00eddrica, busca contribuir a una miner\u00eda m\u00e1s sustentable.<\/p>\n<p>Exponor 2024 -del 3 al 6 de junio- cuenta con el respaldo de sus socios estrat\u00e9gicos Albemarle, Antofagasta Minerals, Codelco, Escondida|BHP, Glencore, Minera El Abra, Pan American Silver, Sierra Gorda SCM, Spence|BHP y SQM, junto al patrocinio de Aprimin, Consejo Minero, Generadoras de Chile, InvestChile, Ministerios de Econom\u00eda, Miner\u00eda y Energ\u00eda, Gobierno Regional, ProChile, Sofofa y Sonami.<\/p>\n<\/div>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p><span class='published'>Chile | 2024-03-20<\/span><\/p>\n<p>Ofrecer innovaciones, nuevas tecnolog\u00edas, equipamiento y m\u00e1s para, responder a las necesidades de la industria minera y energ\u00e9tica, forman parte de la oferta que traer\u00e1 a nuestro pa\u00eds.<\/p>\n","protected":false},"author":26,"featured_media":165356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/posts\/165355"}],"collection":[{"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/comments?post=165355"}],"version-history":[{"count":1,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/posts\/165355\/revisions"}],"predecessor-version":[{"id":165357,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/posts\/165355\/revisions\/165357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/media\/165356"}],"wp:attachment":[{"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/media?parent=165355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/categories?post=165355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalminero.com\/wp\/wp-json\/wp\/v2\/tags?post=165355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}